{"id":9172,"date":"2022-01-31T08:44:58","date_gmt":"2022-01-31T08:44:58","guid":{"rendered":"https:\/\/www.music.mahidol.ac.th\/blog\/mou_childdevelopment_musictherapy\/"},"modified":"2022-01-31T08:44:58","modified_gmt":"2022-01-31T08:44:58","slug":"mou_childdevelopment_musictherapy","status":"publish","type":"blog","link":"https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/","title":{"rendered":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22  \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272876399_10160339358541844_1787311154406048111_n-2.jpg\" alt=\"\" class=\"wp-image-7454\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272876399_10160339358541844_1787311154406048111_n-2.jpg 2048w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272876399_10160339358541844_1787311154406048111_n-2-300x200.jpg 300w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272876399_10160339358541844_1787311154406048111_n-2-1024x683.jpg 1024w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272876399_10160339358541844_1787311154406048111_n-2-768x512.jpg 768w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272876399_10160339358541844_1787311154406048111_n-2-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>31 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2565 &#8211; \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e14\u0e23.\u0e13\u0e23\u0e07\u0e04\u0e4c \u0e1b\u0e23\u0e32\u0e07\u0e04\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e25\u0e07\u0e19\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e2d\u0e14\u0e34\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e43\u0e19\u0e21\u0e34\u0e15\u0e34\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e42\u0e14\u0e22\u0e1e\u0e34\u0e18\u0e35\u0e25\u0e07\u0e19\u0e32\u0e21\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e13 \u0e2b\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272947102_10160339358371844_5442270096695630161_n-1024x683.jpg\" alt=\"\" data-id=\"7438\" data-full-url=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272947102_10160339358371844_5442270096695630161_n.jpg\" data-link=\"https:\/\/www.music.mahidol.ac.th\/?attachment_id=7438\" class=\"wp-image-7439\" srcset=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272947102_10160339358371844_5442270096695630161_n-1024x683.jpg 1024w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272947102_10160339358371844_5442270096695630161_n-300x200.jpg 300w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272947102_10160339358371844_5442270096695630161_n-768x512.jpg 768w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272947102_10160339358371844_5442270096695630161_n-1536x1024.jpg 1536w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272947102_10160339358371844_5442270096695630161_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273013398_10160339358471844_5379740391926122946_n-1024x683.jpg\" alt=\"\" data-id=\"7436\" data-full-url=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273013398_10160339358471844_5379740391926122946_n.jpg\" data-link=\"https:\/\/www.music.mahidol.ac.th\/?attachment_id=7436\" class=\"wp-image-7437\" srcset=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273013398_10160339358471844_5379740391926122946_n-1024x683.jpg 1024w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273013398_10160339358471844_5379740391926122946_n-300x200.jpg 300w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273013398_10160339358471844_5379740391926122946_n-768x512.jpg 768w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273013398_10160339358471844_5379740391926122946_n-1536x1024.jpg 1536w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273013398_10160339358471844_5379740391926122946_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273030113_10160339358286844_6121538474222235727_n-1024x683.jpg\" alt=\"\" data-id=\"7434\" data-full-url=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273030113_10160339358286844_6121538474222235727_n.jpg\" data-link=\"https:\/\/www.music.mahidol.ac.th\/?attachment_id=7434\" class=\"wp-image-7435\" srcset=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273030113_10160339358286844_6121538474222235727_n-1024x683.jpg 1024w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273030113_10160339358286844_6121538474222235727_n-300x200.jpg 300w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273030113_10160339358286844_6121538474222235727_n-768x512.jpg 768w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273030113_10160339358286844_6121538474222235727_n-1536x1024.jpg 1536w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/273030113_10160339358286844_6121538474222235727_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272892236_10160339358836844_675996779935619400_n-1024x683.jpg\" alt=\"\" data-id=\"7444\" data-full-url=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272892236_10160339358836844_675996779935619400_n.jpg\" data-link=\"https:\/\/www.music.mahidol.ac.th\/?attachment_id=7444\" class=\"wp-image-7445\" srcset=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272892236_10160339358836844_675996779935619400_n-1024x683.jpg 1024w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272892236_10160339358836844_675996779935619400_n-300x200.jpg 300w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272892236_10160339358836844_675996779935619400_n-768x512.jpg 768w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272892236_10160339358836844_675996779935619400_n-1536x1024.jpg 1536w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272892236_10160339358836844_675996779935619400_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272905918_10160339358311844_3026746452199480559_n-1024x683.jpg\" alt=\"\" data-id=\"7442\" data-full-url=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272905918_10160339358311844_3026746452199480559_n.jpg\" data-link=\"https:\/\/www.music.mahidol.ac.th\/?attachment_id=7442\" class=\"wp-image-7443\" srcset=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272905918_10160339358311844_3026746452199480559_n-1024x683.jpg 1024w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272905918_10160339358311844_3026746452199480559_n-300x200.jpg 300w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272905918_10160339358311844_3026746452199480559_n-768x512.jpg 768w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272905918_10160339358311844_3026746452199480559_n-1536x1024.jpg 1536w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272905918_10160339358311844_3026746452199480559_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272809822_10160339358676844_2477904858338170098_n-1024x683.jpg\" alt=\"\" data-id=\"7440\" data-full-url=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272809822_10160339358676844_2477904858338170098_n.jpg\" data-link=\"https:\/\/www.music.mahidol.ac.th\/?attachment_id=7440\" class=\"wp-image-7441\" srcset=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272809822_10160339358676844_2477904858338170098_n-1024x683.jpg 1024w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272809822_10160339358676844_2477904858338170098_n-300x200.jpg 300w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272809822_10160339358676844_2477904858338170098_n-768x512.jpg 768w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272809822_10160339358676844_2477904858338170098_n-1536x1024.jpg 1536w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272809822_10160339358676844_2477904858338170098_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272881446_10160339358701844_2095791079589852529_n-1024x683.jpg\" alt=\"\" data-id=\"7446\" data-full-url=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272881446_10160339358701844_2095791079589852529_n.jpg\" data-link=\"https:\/\/www.music.mahidol.ac.th\/?attachment_id=7446\" class=\"wp-image-7447\" srcset=\"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272881446_10160339358701844_2095791079589852529_n-1024x683.jpg 1024w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272881446_10160339358701844_2095791079589852529_n-300x200.jpg 300w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272881446_10160339358701844_2095791079589852529_n-768x512.jpg 768w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272881446_10160339358701844_2095791079589852529_n-1536x1024.jpg 1536w, https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272881446_10160339358701844_2095791079589852529_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\"><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19<\/p>\n","protected":false},"featured_media":7447,"template":"","tags":[349,321,323,357,358,359],"blog_category":[55,54],"class_list":["post-9172","blog","type-blog","status-publish","has-post-thumbnail","hentry","tag-betterwithmusic-th","tag-doortoyourstage-th","tag-mahidolmusic-th","tag-mou-th","tag-music-therapy-th","tag-research-th","blog_category-education","blog_category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 - Mahidol Music<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 - Mahidol Music\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/\" \/>\n<meta property=\"og:site_name\" content=\"Mahidol Music\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272876399_10160339358541844_1787311154406048111_n-2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/blog\\\/mou_childdevelopment_musictherapy\\\/\",\"url\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/blog\\\/mou_childdevelopment_musictherapy\\\/\",\"name\":\"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 - Mahidol Music\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/blog\\\/mou_childdevelopment_musictherapy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/blog\\\/mou_childdevelopment_musictherapy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/272881446_10160339358701844_2095791079589852529_n.jpg\",\"datePublished\":\"2022-01-31T08:44:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/blog\\\/mou_childdevelopment_musictherapy\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/blog\\\/mou_childdevelopment_musictherapy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/blog\\\/mou_childdevelopment_musictherapy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/272881446_10160339358701844_2095791079589852529_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/272881446_10160339358701844_2095791079589852529_n.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/blog\\\/mou_childdevelopment_musictherapy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/\",\"name\":\"Mahidol Music\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/#organization\",\"name\":\"Mahidol Music\",\"url\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/mahidol-music-logo-lg.svg\",\"contentUrl\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/mahidol-music-logo-lg.svg\",\"width\":126,\"height\":58,\"caption\":\"Mahidol Music\"},\"image\":{\"@id\":\"https:\\\/\\\/www.music.mahidol.ac.th\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 - Mahidol Music","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 - Mahidol Music","og_description":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19","og_url":"https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/","og_site_name":"Mahidol Music","og_image":[{"url":"http:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272876399_10160339358541844_1787311154406048111_n-2.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/","url":"https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/","name":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 - Mahidol Music","isPartOf":{"@id":"https:\/\/www.music.mahidol.ac.th\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/#primaryimage"},"image":{"@id":"https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272881446_10160339358701844_2095791079589852529_n.jpg","datePublished":"2022-01-31T08:44:58+00:00","breadcrumb":{"@id":"https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/#primaryimage","url":"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272881446_10160339358701844_2095791079589852529_n.jpg","contentUrl":"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2022\/01\/272881446_10160339358701844_2095791079589852529_n.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/www.music.mahidol.ac.th\/th\/blog\/mou_childdevelopment_musictherapy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.music.mahidol.ac.th\/th\/"},{"@type":"ListItem","position":2,"name":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e14\u0e38\u0e23\u0e34\u0e22\u0e32\u0e07\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19"}]},{"@type":"WebSite","@id":"https:\/\/www.music.mahidol.ac.th\/th\/#website","url":"https:\/\/www.music.mahidol.ac.th\/th\/","name":"Mahidol Music","description":"","publisher":{"@id":"https:\/\/www.music.mahidol.ac.th\/th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.music.mahidol.ac.th\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.music.mahidol.ac.th\/th\/#organization","name":"Mahidol Music","url":"https:\/\/www.music.mahidol.ac.th\/th\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.music.mahidol.ac.th\/th\/#\/schema\/logo\/image\/","url":"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2021\/11\/mahidol-music-logo-lg.svg","contentUrl":"https:\/\/www.music.mahidol.ac.th\/wp-content\/uploads\/2021\/11\/mahidol-music-logo-lg.svg","width":126,"height":58,"caption":"Mahidol Music"},"image":{"@id":"https:\/\/www.music.mahidol.ac.th\/th\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.music.mahidol.ac.th\/th\/wp-json\/wp\/v2\/blog\/9172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.music.mahidol.ac.th\/th\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.music.mahidol.ac.th\/th\/wp-json\/wp\/v2\/types\/blog"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.music.mahidol.ac.th\/th\/wp-json\/wp\/v2\/media\/7447"}],"wp:attachment":[{"href":"https:\/\/www.music.mahidol.ac.th\/th\/wp-json\/wp\/v2\/media?parent=9172"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.music.mahidol.ac.th\/th\/wp-json\/wp\/v2\/tags?post=9172"},{"taxonomy":"blog_category","embeddable":true,"href":"https:\/\/www.music.mahidol.ac.th\/th\/wp-json\/wp\/v2\/blog_category?post=9172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}